{"id":2253,"date":"2021-05-05T17:04:44","date_gmt":"2021-05-05T15:04:44","guid":{"rendered":"https:\/\/duemo-camperpark-aguilas.es\/stellplaetze\/"},"modified":"2024-03-19T14:54:34","modified_gmt":"2024-03-19T13:54:34","slug":"emplacements","status":"publish","type":"page","link":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/","title":{"rendered":"Emplacements"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2253","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emplacements - D\u00dcMO Camperpark - Aguilas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emplacements - D\u00dcMO Camperpark - Aguilas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00dcMO Camperpark - Aguilas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T13:54:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/emplacements\\\/\",\"url\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/emplacements\\\/\",\"name\":\"Emplacements - D\u00dcMO Camperpark - Aguilas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/#website\"},\"datePublished\":\"2021-05-05T15:04:44+00:00\",\"dateModified\":\"2024-03-19T13:54:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/emplacements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/emplacements\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/emplacements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emplacements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/\",\"name\":\"D\u00dcMO Camperpark - Aguilas\",\"description\":\"Wohnmobile mieten bei D\u00fcmo Reisemobile - Die Wohnmobilvermietung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/duemo-camperpark-aguilas.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emplacements - D\u00dcMO Camperpark - Aguilas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/","og_locale":"fr_FR","og_type":"article","og_title":"Emplacements - D\u00dcMO Camperpark - Aguilas","og_url":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/","og_site_name":"D\u00dcMO Camperpark - Aguilas","article_modified_time":"2024-03-19T13:54:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/","url":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/","name":"Emplacements - D\u00dcMO Camperpark - Aguilas","isPartOf":{"@id":"https:\/\/duemo-camperpark-aguilas.es\/fr\/#website"},"datePublished":"2021-05-05T15:04:44+00:00","dateModified":"2024-03-19T13:54:34+00:00","breadcrumb":{"@id":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/duemo-camperpark-aguilas.es\/fr\/emplacements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/duemo-camperpark-aguilas.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Emplacements"}]},{"@type":"WebSite","@id":"https:\/\/duemo-camperpark-aguilas.es\/fr\/#website","url":"https:\/\/duemo-camperpark-aguilas.es\/fr\/","name":"D\u00dcMO Camperpark - Aguilas","description":"Wohnmobile mieten bei D\u00fcmo Reisemobile - Die Wohnmobilvermietung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/duemo-camperpark-aguilas.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/pages\/2253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/comments?post=2253"}],"version-history":[{"count":2,"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/pages\/2253\/revisions"}],"predecessor-version":[{"id":2260,"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/pages\/2253\/revisions\/2260"}],"wp:attachment":[{"href":"https:\/\/duemo-camperpark-aguilas.es\/fr\/wp-json\/wp\/v2\/media?parent=2253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}